{"id":84314,"date":"2021-01-15T14:51:16","date_gmt":"2021-01-15T13:51:16","guid":{"rendered":"https:\/\/www.avacecolours.com\/fr\/product\/s-6020-y20r\/"},"modified":"2023-03-24T17:36:45","modified_gmt":"2023-03-24T16:36:45","slug":"s-6020-y20r","status":"publish","type":"product","link":"https:\/\/www.avacecolours.com\/fr\/product\/s-6020-y20r\/","title":{"rendered":"NCS S 6020 Y20R"},"content":{"rendered":"<p><strong>NCS S 6020 Y20R<\/strong> sera de couleurs assorties, fabriqu\u00e9 et livr\u00e9 sur votre site en France sous 7 jours ouvrables. La quantit\u00e9 minimale de commande pour ce service de poudres en petits lots en express est de 20 kg. Permet de r\u00e9duire les d\u00e9chets et les co\u00fbts inutiles.<\/p>\n<p><strong>NCS S 6020 Y20R<\/strong> est disponible en polyester architectural en finition brillante, semi-brillante ou mate . Conforme aux exigences de la norme EN 12206 pour l&#8217;aluminium et de la norme EN 13438 pour l&#8217;acier galvanis\u00e9. Compte tenu des petites quantit\u00e9s produites, il n&#8217;est pas \u00e9conomiquement viable de soumettre les poudres pour la certification Qualicoat.<\/p>\n<p>Les r\u00e9dacteurs de cahier des charges et les concepteurs recherchent un plus grand choix de couleurs parmi les gammes NCS, RAL Design et Pantone. La capacit\u00e9 de fabriquer un minimum de 20 kg de poudre de couleurs comme <strong>NCS S 6020 Y20R<\/strong> et de livrer en sept jours ouvrables est une innovation de service majeure d&#8217;Avace.<\/p>\n<p>Le service de couleurs en petits lots en express d&#8217;AVACE a lib\u00e9r\u00e9 La France en couleurs pour la d\u00e9finition de tendances par les architectes, les r\u00e9dacteurs de cahier des charges et les concepteurs fran\u00e7ais.<\/p>\n<p>Le service de couleurs en petit lots est disponible dans d&#8217;autres types de poudre tels que l&#8217;\u00e9poxy et le polyester \u00e9poxy, dans une vari\u00e9t\u00e9 de niveaux de brillance, de textures et de simili cuir. Pour de plus amples renseignements sur la couleur de votre choix, veuillez envoyer votre demande par courriel \u00e0 <a href=\"mailto:sales@avacecolours.com\">sales@avacecolours.com<\/a>.<\/p>\n<p>Avace s&#8217;efforce de fabriquer pr\u00e9cis\u00e9ment la quantit\u00e9 que vous commandez, mais notez que des variations de +\/- 10 % peuvent se produire dans le processus de fabrication. Les quantit\u00e9s inf\u00e9rieures seront cr\u00e9dit\u00e9es et les quantit\u00e9s sup\u00e9rieures seront factur\u00e9es au tarif du kilo.<\/p>\n<p>Les couleurs repr\u00e9sent\u00e9es sur le site sont fournies \u00e0 titre indicatif uniquement. La couleur affich\u00e9e d\u00e9pend de votre moniteur et de votre navigateur. La poudre r\u00e9elle est conforme \u00e0 la norme NCS officielle.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ProductName] sera de couleurs assorties, fabriqu\u00e9 et livr\u00e9 sur votre site en France sous 7 jours ouvrables. La quantit\u00e9 minimale de commande pour ce service de poudres en petits lots en express est de 20 kg.<\/p>\n","protected":false},"featured_media":17573,"template":"","meta":{"_acf_changed":false},"product_cat":[84,97],"product_tag":[],"class_list":{"0":"post-84314","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ncs-1950","7":"product_cat-s-5500-s-6530","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-variable","15":"has-default-attributes"},"acf":[],"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":{"40":"15.50","60":"14.20","80":"13.75","100":"10.95"},"tiered_pricing_percentage_rules":[],"tiered_pricing_minimum":20,"tiered_pricing_roles_data":[],"_links":{"self":[{"href":"https:\/\/www.avacecolours.com\/fr\/wp-json\/wp\/v2\/product\/84314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.avacecolours.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.avacecolours.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.avacecolours.com\/fr\/wp-json\/wp\/v2\/media\/17573"}],"wp:attachment":[{"href":"https:\/\/www.avacecolours.com\/fr\/wp-json\/wp\/v2\/media?parent=84314"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.avacecolours.com\/fr\/wp-json\/wp\/v2\/product_cat?post=84314"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.avacecolours.com\/fr\/wp-json\/wp\/v2\/product_tag?post=84314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}