{"id":77397,"date":"2021-02-23T17:11:39","date_gmt":"2021-02-23T16:11:39","guid":{"rendered":"https:\/\/www.avacecolours.com\/es\/product\/s-0560-y40r\/"},"modified":"2022-08-03T12:22:05","modified_gmt":"2022-08-03T10:22:05","slug":"s-0560-y40r","status":"publish","type":"product","link":"https:\/\/www.avacecolours.com\/es\/product\/s-0560-y40r\/","title":{"rendered":"NCS S 0560 Y40R"},"content":{"rendered":"<p><strong>NCS S 0560 Y40R<\/strong> coincidir\u00e1 el color, lo fabricar\u00e1 y lo entregar\u00e1 a su lugar en Espa\u00f1a en 9 d\u00edas laborables. La cantidad m\u00ednima de pedido para este servicio de polvo en peque\u00f1os lotes por v\u00eda r\u00e1pida es de 20 kg. Reduciendo residuos y costes innecesarios.<\/p>\n<p><strong>NCS S 0560 Y40R<\/strong> est\u00e1 disponible en poli\u00e9ster arquitect\u00f3nico con acabado brillante, semibrillante o mate. Cumplimiento de los requisitos de la norma EN 12206 para aluminio y la norma EN 13438 para acero galvanizado. En vista de las peque\u00f1as cantidades producidas, no es econ\u00f3micamente viable presentar polvos para la certificaci\u00f3n Qualicoat.<\/p>\n<p>Especificadores y dise\u00f1adores est\u00e1n buscando una mayor elecci\u00f3n de colores seleccionando colores de las gamas NCS, RAL Design y Pantone. La capacidad de fabricar un m\u00ednimo de 20 kg de colores en polvo como <strong>NCS S 0560 Y40R<\/strong> y la entrega en nueve d\u00edas h\u00e1biles es una importante innovaci\u00f3n de servicio de Avace.<\/p>\n<p>El servicio AVACE r\u00e1pido de producci\u00f3n de peque\u00f1os lotes de color ha dado lugar a Espa\u00f1a en color para establecer tendencias en arquitectos, especificadores y dise\u00f1adores espa\u00f1oles.<\/p>\n<p>El servicio de fabricaci\u00f3n de peque\u00f1os lotes de color est\u00e1 disponible en otros tipos de polvo como epoxy y poli\u00e9ster epoxy, en una variedad de niveles de brillo, texturas y cuero sint\u00e9tico. Para obtener m\u00e1s informaci\u00f3n sobre el color de su elecci\u00f3n, env\u00ede su consulta por correo electr\u00f3nico a <a href=\"mailto:sales@avacecolours.com\">sales@avacecolours.com<\/a>.<\/p>\n<p>Avace se esfuerza por fabricar con precisi\u00f3n la cantidad que usted pide. Sin embargo, tenga en cuenta que puede variar entre un +10 % y un -10 % durante el proceso de fabricaci\u00f3n. Los pedidos incompletos se reembolsar\u00e1n y los pedidos en exceso se cobrar\u00e1n seg\u00fan la tarifa por kilo.<\/p>\n<p>Los colores representados en el sitio web son solo orientativos. El color que se muestra depender\u00e1 de su monitor y del navegador. El polvo en s\u00ed se ajusta a la norma oficial de NCS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ProductName] coincidir\u00e1 el color, lo fabricar\u00e1 y lo entregar\u00e1 a su lugar en Espa\u00f1a en 9 d\u00edas laborables. La cantidad m\u00ednima de pedido para este servicio de polvo en peque\u00f1os lotes por v\u00eda r\u00e1pida es de 20 kg. Reduciendo residuos y costes innecesarios.<\/p>\n","protected":false},"featured_media":77399,"template":"","meta":{"_acf_changed":false},"product_cat":[23,22],"product_tag":[],"class_list":["post-77397","product","type-product","status-publish","has-post-thumbnail","product_cat-s-0300-s-0907","product_cat-ncs-1950","pa_brillance-brillante","pa_brillance-mate","pa_brillance-semibrillante","pa_color-colores-fuertes","pa_entrega-fabricado-y-entregado-en-9-dias-laborables","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":{"40":"16.95","60":"15.70","80":"15.25","100":"12.50"},"tiered_pricing_percentage_rules":[],"tiered_pricing_minimum":20,"tiered_pricing_roles_data":[],"_links":{"self":[{"href":"https:\/\/www.avacecolours.com\/es\/wp-json\/wp\/v2\/product\/77397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.avacecolours.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.avacecolours.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.avacecolours.com\/es\/wp-json\/wp\/v2\/media\/77399"}],"wp:attachment":[{"href":"https:\/\/www.avacecolours.com\/es\/wp-json\/wp\/v2\/media?parent=77397"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.avacecolours.com\/es\/wp-json\/wp\/v2\/product_cat?post=77397"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.avacecolours.com\/es\/wp-json\/wp\/v2\/product_tag?post=77397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}